{"id":6444,"date":"2024-03-26T14:43:23","date_gmt":"2024-03-26T13:43:23","guid":{"rendered":"https:\/\/gandan-yourte.com\/senza-categoria\/palo-della-porta-5-pareti-colore-legno\/"},"modified":"2024-03-26T14:43:23","modified_gmt":"2024-03-26T13:43:23","slug":"palo-della-porta-5-pareti-colore-legno","status":"publish","type":"product","link":"https:\/\/gandan-yourte.com\/it\/opzioni-e-ricambi\/lavori-in-legno\/persico\/palo-della-porta-5-pareti-colore-legno\/","title":{"rendered":"Palo della porta &#8211; 5 pareti &#8211; Colore legno"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":5555,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[223],"product_tag":[],"class_list":["post-6444","product","type-product","status-publish","has-post-thumbnail","product_cat-persico","first","instock","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Palo della porta - 5 pareti - Colore legno | Gandan Yourte<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gandan-yourte.com\/it\/opzioni-e-ricambi\/lavori-in-legno\/persico\/palo-della-porta-5-pareti-colore-legno\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Palo della porta - 5 pareti - Colore legno | Gandan Yourte\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gandan-yourte.com\/it\/opzioni-e-ricambi\/lavori-in-legno\/persico\/palo-della-porta-5-pareti-colore-legno\/\" \/>\n<meta property=\"og:site_name\" content=\"Gandan Yourte\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gandan-yourte.com\/wp-content\/uploads\/toono-intercontinental-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gandan-yourte.com\\\/it\\\/opzioni-e-ricambi\\\/lavori-in-legno\\\/persico\\\/palo-della-porta-5-pareti-colore-legno\\\/\",\"url\":\"https:\\\/\\\/gandan-yourte.com\\\/it\\\/opzioni-e-ricambi\\\/lavori-in-legno\\\/persico\\\/palo-della-porta-5-pareti-colore-legno\\\/\",\"name\":\"Palo della porta - 5 pareti - Colore legno | Gandan Yourte\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gandan-yourte.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gandan-yourte.com\\\/it\\\/opzioni-e-ricambi\\\/lavori-in-legno\\\/persico\\\/palo-della-porta-5-pareti-colore-legno\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gandan-yourte.com\\\/it\\\/opzioni-e-ricambi\\\/lavori-in-legno\\\/persico\\\/palo-della-porta-5-pareti-colore-legno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gandan-yourte.com\\\/wp-content\\\/uploads\\\/toono-intercontinental-1-scaled.jpg\",\"datePublished\":\"2024-03-26T13:43:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gandan-yourte.com\\\/it\\\/opzioni-e-ricambi\\\/lavori-in-legno\\\/persico\\\/palo-della-porta-5-pareti-colore-legno\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gandan-yourte.com\\\/it\\\/opzioni-e-ricambi\\\/lavori-in-legno\\\/persico\\\/palo-della-porta-5-pareti-colore-legno\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/gandan-yourte.com\\\/it\\\/opzioni-e-ricambi\\\/lavori-in-legno\\\/persico\\\/palo-della-porta-5-pareti-colore-legno\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gandan-yourte.com\\\/wp-content\\\/uploads\\\/toono-intercontinental-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/gandan-yourte.com\\\/wp-content\\\/uploads\\\/toono-intercontinental-1-scaled.jpg\",\"width\":2560,\"height\":1700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gandan-yourte.com\\\/it\\\/opzioni-e-ricambi\\\/lavori-in-legno\\\/persico\\\/palo-della-porta-5-pareti-colore-legno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/gandan-yourte.com\\\/it\\\/pagina-iniziale\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Negozio\",\"item\":\"https:\\\/\\\/gandan-yourte.com\\\/it\\\/negozio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Opzioni e ricambi\",\"item\":\"https:\\\/\\\/gandan-yourte.com\\\/it\\\/opzioni-e-ricambi\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Lavori in legno\",\"item\":\"https:\\\/\\\/gandan-yourte.com\\\/it\\\/opzioni-e-ricambi\\\/lavori-in-legno\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Persico\",\"item\":\"https:\\\/\\\/gandan-yourte.com\\\/it\\\/opzioni-e-ricambi\\\/lavori-in-legno\\\/persico\\\/\"},{\"@type\":\"ListItem\",\"position\":6,\"name\":\"Palo della porta &#8211; 5 pareti &#8211; Colore legno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gandan-yourte.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/gandan-yourte.com\\\/it\\\/\",\"name\":\"Gandan Yourte\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/gandan-yourte.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gandan-yourte.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gandan-yourte.com\\\/it\\\/#organization\",\"name\":\"Gandan Yourte\",\"url\":\"https:\\\/\\\/gandan-yourte.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/gandan-yourte.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gandan-yourte.com\\\/wp-content\\\/uploads\\\/cropped-Logo-essai-1-GY-haute-def-avec-transparence-3508x1772px-1.png\",\"contentUrl\":\"https:\\\/\\\/gandan-yourte.com\\\/wp-content\\\/uploads\\\/cropped-Logo-essai-1-GY-haute-def-avec-transparence-3508x1772px-1.png\",\"width\":3506,\"height\":1772,\"caption\":\"Gandan Yourte\"},\"image\":{\"@id\":\"https:\\\/\\\/gandan-yourte.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Palo della porta - 5 pareti - Colore legno | Gandan Yourte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gandan-yourte.com\/it\/opzioni-e-ricambi\/lavori-in-legno\/persico\/palo-della-porta-5-pareti-colore-legno\/","og_locale":"it_IT","og_type":"article","og_title":"Palo della porta - 5 pareti - Colore legno | Gandan Yourte","og_url":"https:\/\/gandan-yourte.com\/it\/opzioni-e-ricambi\/lavori-in-legno\/persico\/palo-della-porta-5-pareti-colore-legno\/","og_site_name":"Gandan Yourte","og_image":[{"width":2560,"height":1700,"url":"https:\/\/gandan-yourte.com\/wp-content\/uploads\/toono-intercontinental-1-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/gandan-yourte.com\/it\/opzioni-e-ricambi\/lavori-in-legno\/persico\/palo-della-porta-5-pareti-colore-legno\/","url":"https:\/\/gandan-yourte.com\/it\/opzioni-e-ricambi\/lavori-in-legno\/persico\/palo-della-porta-5-pareti-colore-legno\/","name":"Palo della porta - 5 pareti - Colore legno | Gandan Yourte","isPartOf":{"@id":"https:\/\/gandan-yourte.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gandan-yourte.com\/it\/opzioni-e-ricambi\/lavori-in-legno\/persico\/palo-della-porta-5-pareti-colore-legno\/#primaryimage"},"image":{"@id":"https:\/\/gandan-yourte.com\/it\/opzioni-e-ricambi\/lavori-in-legno\/persico\/palo-della-porta-5-pareti-colore-legno\/#primaryimage"},"thumbnailUrl":"https:\/\/gandan-yourte.com\/wp-content\/uploads\/toono-intercontinental-1-scaled.jpg","datePublished":"2024-03-26T13:43:23+00:00","breadcrumb":{"@id":"https:\/\/gandan-yourte.com\/it\/opzioni-e-ricambi\/lavori-in-legno\/persico\/palo-della-porta-5-pareti-colore-legno\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gandan-yourte.com\/it\/opzioni-e-ricambi\/lavori-in-legno\/persico\/palo-della-porta-5-pareti-colore-legno\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/gandan-yourte.com\/it\/opzioni-e-ricambi\/lavori-in-legno\/persico\/palo-della-porta-5-pareti-colore-legno\/#primaryimage","url":"https:\/\/gandan-yourte.com\/wp-content\/uploads\/toono-intercontinental-1-scaled.jpg","contentUrl":"https:\/\/gandan-yourte.com\/wp-content\/uploads\/toono-intercontinental-1-scaled.jpg","width":2560,"height":1700},{"@type":"BreadcrumbList","@id":"https:\/\/gandan-yourte.com\/it\/opzioni-e-ricambi\/lavori-in-legno\/persico\/palo-della-porta-5-pareti-colore-legno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/gandan-yourte.com\/it\/pagina-iniziale\/"},{"@type":"ListItem","position":2,"name":"Negozio","item":"https:\/\/gandan-yourte.com\/it\/negozio\/"},{"@type":"ListItem","position":3,"name":"Opzioni e ricambi","item":"https:\/\/gandan-yourte.com\/it\/opzioni-e-ricambi\/"},{"@type":"ListItem","position":4,"name":"Lavori in legno","item":"https:\/\/gandan-yourte.com\/it\/opzioni-e-ricambi\/lavori-in-legno\/"},{"@type":"ListItem","position":5,"name":"Persico","item":"https:\/\/gandan-yourte.com\/it\/opzioni-e-ricambi\/lavori-in-legno\/persico\/"},{"@type":"ListItem","position":6,"name":"Palo della porta &#8211; 5 pareti &#8211; Colore legno"}]},{"@type":"WebSite","@id":"https:\/\/gandan-yourte.com\/it\/#website","url":"https:\/\/gandan-yourte.com\/it\/","name":"Gandan Yourte","description":"","publisher":{"@id":"https:\/\/gandan-yourte.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gandan-yourte.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/gandan-yourte.com\/it\/#organization","name":"Gandan Yourte","url":"https:\/\/gandan-yourte.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/gandan-yourte.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/gandan-yourte.com\/wp-content\/uploads\/cropped-Logo-essai-1-GY-haute-def-avec-transparence-3508x1772px-1.png","contentUrl":"https:\/\/gandan-yourte.com\/wp-content\/uploads\/cropped-Logo-essai-1-GY-haute-def-avec-transparence-3508x1772px-1.png","width":3506,"height":1772,"caption":"Gandan Yourte"},"image":{"@id":"https:\/\/gandan-yourte.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/gandan-yourte.com\/it\/wp-json\/wp\/v2\/product\/6444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gandan-yourte.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gandan-yourte.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gandan-yourte.com\/it\/wp-json\/wp\/v2\/comments?post=6444"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gandan-yourte.com\/it\/wp-json\/wp\/v2\/media\/5555"}],"wp:attachment":[{"href":"https:\/\/gandan-yourte.com\/it\/wp-json\/wp\/v2\/media?parent=6444"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gandan-yourte.com\/it\/wp-json\/wp\/v2\/product_brand?post=6444"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gandan-yourte.com\/it\/wp-json\/wp\/v2\/product_cat?post=6444"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gandan-yourte.com\/it\/wp-json\/wp\/v2\/product_tag?post=6444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}